{"id":8099,"date":"2020-08-16T13:00:00","date_gmt":"2020-08-16T11:00:00","guid":{"rendered":"https:\/\/svetkamene.eu\/?p=8099"},"modified":"2022-06-14T21:39:59","modified_gmt":"2022-06-14T19:39:59","slug":"zentrum-fur-musikstudien-in-santiago-de-compostella","status":"publish","type":"post","link":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/","title":{"rendered":"ZENTRUM F\u00dcR MUSIKSTUDIEN IN SANTIAGO DE COMPOSTELLA"},"content":{"rendered":"\n<p><strong>Ist Stein ein plastisches Material? Kann er dynamisch sein? Regt er die Fantasie an? Es gibt Projekte, die positive Antworten auf diese und \u00e4hnliche Fragen geben. Das Wichtigste ist, sich von stereotypem Denken zu befreien und der Fantasie freien Lauf zu lassen.<\/strong><\/p>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>In der letzten Ausgabe des Magazins haben wir Ihnen den Sitz der Autoren- und Verlegervereinigung SGAE vorgestellt &#8211; ein Geb\u00e4ude im Viertel Vista Alegre in Santiago de Compostella, Spanien. In demselben Viertel befindet sich ein weiteres ungew\u00f6hnliches Projekt desselben Architekturb\u00fcros: das Ensemble Studio.<\/p>\n\n\n\n<p>Bei diesem Projekt handelt es sich um den Bau des Zentrums f\u00fcr Musikstudien, in dem viele gro\u00dfe Musiker studiert haben, darunter auch Mitglieder des Galicischen Symphonieorchesters.<\/p>\n\n\n\n<p>Der Autor des Projekts &#8211; Ant\u00f3n Garc\u00eda-Abril &#8211; nahm das Angebot unter der Voraussetzung an, dass es sich um ein Geb\u00e4ude handeln w\u00fcrde, dessen visuelle Wahrnehmung je nach der Entfernung, aus der es betrachtet wird, variieren w\u00fcrde. Die vorgelegten Fotos best\u00e4tigen, dass dieses Ziel erreicht wurde.<\/p>\n\n\n\n<p>Aus der Ferne sieht das Geb\u00e4ude aus wie ein Stein, der auf einen gr\u00fcnen Grasteppich gefallen ist. F\u00fcr die meisten Betrachter ist dieses Objekt &#8211; wie der Sch\u00f6pfer des Projekts es nennt &#8211; eine &#8222;definitionslose&#8220; Form. Erst wenn man sich dem Geb\u00e4ude n\u00e4hert, bemerkt man die subtilen, gebrochenen Linien der W\u00e4nde und vertikalen Fenster, die ein ansonsten homogenes Geb\u00e4ude in ein interessantes Schauspiel verwandeln, das von einem Spiel mit Licht und Schatten lebt. Aus noch gr\u00f6\u00dferer N\u00e4he kann man dann die bewusst geschaffenen Fehler im Material wahrnehmen, deren unebene Oberfl\u00e4che und raue Verarbeitung eine einzigartige Atmosph\u00e4re schaffen. Gleichzeitig erleichtern die beleuchteten Fenster visuell den massiven, weithin sichtbaren Bauk\u00f6rper.<\/p>\n\n\n\n<p>Der Designer wollte einen Effekt der Gegens\u00e4tzlichkeit und Dualit\u00e4t des Geb\u00e4udes erreichen. Der einfache Block, der in verschiedenen Ma\u00dfst\u00e4ben dargestellt ist, soll verschiedene Kompliziertheitsgrade darstellen. Die Verzerrungen, die durch die Harmonie des Gesamtk\u00f6rpers entstehen, machen sowohl die Masse als auch den Raum, den das Geb\u00e4ude schafft, interessant.<\/p>\n\n\n\n<p>Die rohe Granitfassade des Geb\u00e4udes verweist im Sinne des Projekts auf die antike Geschichte und Architektur des alten \u00c4gyptens oder Roms, hat aber auch klare Bez\u00fcge zur galicischen Architektur. Die Gestaltung des Geb\u00e4udes selbst wird durch die akustischen Anforderungen bestimmt. Die Hauptr\u00e4ume, die hohen akustischen Anforderungen gen\u00fcgen m\u00fcssen, befinden sich im Untergeschoss. Es handelt sich um gr\u00f6\u00dfere R\u00e4ume, die eine gro\u00dfe Anzahl von Studenten und Zuschauern aufnehmen k\u00f6nnen: Konzertsaal, R\u00e4ume f\u00fcr elektroakustische Instrumente, Schlagzeug usw.<\/p>\n\n\n\n<p>In den oberen Stockwerken gibt es Kommunikationsr\u00e4ume, von denen aus der Zugang zu Klassenr\u00e4umen, kleineren Unterrichtsr\u00e4umen und B\u00fcros m\u00f6glich ist.<\/p>\n\n\n\n<p>Trotz der innovativen Stellung erweckt das Geb\u00e4ude den Eindruck, als bef\u00e4nde es sich schon seit Urzeiten an diesem Ort. Kritiker haben dieses Projekt als Beitrag zu einer neuen Sichtweise auf die Geometrie und die Grundregeln der Architektur gelobt.<\/p>\n\n\n\n<p>Das Geb\u00e4ude wurde im Jahr 2002 errichtet. Die Gesamtfl\u00e4che des Geb\u00e4udes betr\u00e4gt 1&nbsp;700&nbsp;m<sup>2<\/sup>, und die Baukosten beliefen sich auf 3 Millionen Euro.<\/p>\n\n\n\n<p>Weitere Fotos finden Sie unter: <a href=\"http:\/\/www.facebook.com\/KurierKamieniarski\">www.facebook.com\/KurierKamieniarski<\/a><\/p>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-container-2 wp-block-gallery-1 wp-block-gallery has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"640\" height=\"442\" data-id=\"8100\"  src=\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2022\/06\/santiago2-2.jpg\" alt=\"\" class=\"wp-image-8100\" srcset=\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2022\/06\/santiago2-2.jpg 640w, https:\/\/svetkamene.eu\/wp-content\/uploads\/2022\/06\/santiago2-2-300x207.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Foto: <em>Roland Halbe a\u00a0flickr.com<\/em><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Quelle: <a href=\"https:\/\/www.kurierkamieniarski.pl\/artykuly\/o-kamieniu\/513-orodek-studiow-muzycznych-w-santiago-de-compostella.html\">Kurier kamieniarski<\/a><\/p>\n\n\n\n<p>Autor: Kurier Kamieniarski\u00a0\u00a0\u00a0|\u00a0\u00a0\u00a0Publiziert: 3.&nbsp;11.&nbsp;2015<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ist Stein ein plastisches Material? Kann er dynamisch sein? Regt er die Fantasie an? Es&#8230;<\/p>\n","protected":false},"author":13,"featured_media":2494,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[378],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ZENTRUM F\u00dcR MUSIKSTUDIEN IN SANTIAGO DE COMPOSTELLA - Sv\u011bt Kamene<\/title>\n<meta name=\"description\" content=\"Toto za\u0159\u00edzen\u00ed je Centrum hudebn\u00edch studi\u00ed - m\u00edsto, kde postgradu\u00e1ln\u00ed studium absolvovalo mnoho skv\u011bl\u00fdch hudebn\u00edk\u016f,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZENTRUM F\u00dcR MUSIKSTUDIEN IN SANTIAGO DE COMPOSTELLA - Sv\u011bt Kamene\" \/>\n<meta property=\"og:description\" content=\"Toto za\u0159\u00edzen\u00ed je Centrum hudebn\u00edch studi\u00ed - m\u00edsto, kde postgradu\u00e1ln\u00ed studium absolvovalo mnoho skv\u011bl\u00fdch hudebn\u00edk\u016f,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/\" \/>\n<meta property=\"og:site_name\" content=\"Sv\u011bt Kamene\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-16T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-14T19:39:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/santiago1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napsal(a)\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kate\u0159ina Markvartov\u00e1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Odhadovan\u00e1 doba \u010dten\u00ed\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/svetkamene.eu\/#website\",\"url\":\"https:\/\/svetkamene.eu\/\",\"name\":\"Sv\u011bt Kamene\",\"description\":\"Port\u00e1l informuj\u00edc\u00ed o v\u0161em co souvis\u00ed s kamenem\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/svetkamene.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"cs\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/#primaryimage\",\"url\":\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/santiago1.jpg\",\"contentUrl\":\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/santiago1.jpg\",\"width\":640,\"height\":370},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/#webpage\",\"url\":\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/\",\"name\":\"ZENTRUM F\u00dcR MUSIKSTUDIEN IN SANTIAGO DE COMPOSTELLA - Sv\u011bt Kamene\",\"isPartOf\":{\"@id\":\"https:\/\/svetkamene.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/#primaryimage\"},\"datePublished\":\"2020-08-16T11:00:00+00:00\",\"dateModified\":\"2022-06-14T19:39:59+00:00\",\"author\":{\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/9796ccd50eb4bef1ae8524fac2dfbc9a\"},\"description\":\"Toto za\u0159\u00edzen\u00ed je Centrum hudebn\u00edch studi\u00ed - m\u00edsto, kde postgradu\u00e1ln\u00ed studium absolvovalo mnoho skv\u011bl\u00fdch hudebn\u00edk\u016f,\",\"breadcrumb\":{\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\/\/svetkamene.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ZENTRUM F\u00dcR MUSIKSTUDIEN IN SANTIAGO DE COMPOSTELLA\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/9796ccd50eb4bef1ae8524fac2dfbc9a\",\"name\":\"Kate\u0159ina Markvartov\u00e1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9c2d86222d8e1ce7b67da7f6ec0761a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9c2d86222d8e1ce7b67da7f6ec0761a7?s=96&d=mm&r=g\",\"caption\":\"Kate\u0159ina Markvartov\u00e1\"},\"url\":\"https:\/\/svetkamene.eu\/index.php\/author\/ka-markvartovagmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZENTRUM F\u00dcR MUSIKSTUDIEN IN SANTIAGO DE COMPOSTELLA - Sv\u011bt Kamene","description":"Toto za\u0159\u00edzen\u00ed je Centrum hudebn\u00edch studi\u00ed - m\u00edsto, kde postgradu\u00e1ln\u00ed studium absolvovalo mnoho skv\u011bl\u00fdch hudebn\u00edk\u016f,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/","og_locale":"cs_CZ","og_type":"article","og_title":"ZENTRUM F\u00dcR MUSIKSTUDIEN IN SANTIAGO DE COMPOSTELLA - Sv\u011bt Kamene","og_description":"Toto za\u0159\u00edzen\u00ed je Centrum hudebn\u00edch studi\u00ed - m\u00edsto, kde postgradu\u00e1ln\u00ed studium absolvovalo mnoho skv\u011bl\u00fdch hudebn\u00edk\u016f,","og_url":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/","og_site_name":"Sv\u011bt Kamene","article_published_time":"2020-08-16T11:00:00+00:00","article_modified_time":"2022-06-14T19:39:59+00:00","og_image":[{"width":640,"height":370,"url":"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/santiago1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Napsal(a)":"Kate\u0159ina Markvartov\u00e1","Odhadovan\u00e1 doba \u010dten\u00ed":"3 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/svetkamene.eu\/#website","url":"https:\/\/svetkamene.eu\/","name":"Sv\u011bt Kamene","description":"Port\u00e1l informuj\u00edc\u00ed o v\u0161em co souvis\u00ed s kamenem","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svetkamene.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"cs"},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/#primaryimage","url":"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/santiago1.jpg","contentUrl":"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/santiago1.jpg","width":640,"height":370},{"@type":"WebPage","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/#webpage","url":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/","name":"ZENTRUM F\u00dcR MUSIKSTUDIEN IN SANTIAGO DE COMPOSTELLA - Sv\u011bt Kamene","isPartOf":{"@id":"https:\/\/svetkamene.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/#primaryimage"},"datePublished":"2020-08-16T11:00:00+00:00","dateModified":"2022-06-14T19:39:59+00:00","author":{"@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/9796ccd50eb4bef1ae8524fac2dfbc9a"},"description":"Toto za\u0159\u00edzen\u00ed je Centrum hudebn\u00edch studi\u00ed - m\u00edsto, kde postgradu\u00e1ln\u00ed studium absolvovalo mnoho skv\u011bl\u00fdch hudebn\u00edk\u016f,","breadcrumb":{"@id":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/08\/16\/zentrum-fur-musikstudien-in-santiago-de-compostella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/svetkamene.eu\/"},{"@type":"ListItem","position":2,"name":"ZENTRUM F\u00dcR MUSIKSTUDIEN IN SANTIAGO DE COMPOSTELLA"}]},{"@type":"Person","@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/9796ccd50eb4bef1ae8524fac2dfbc9a","name":"Kate\u0159ina Markvartov\u00e1","image":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9c2d86222d8e1ce7b67da7f6ec0761a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c2d86222d8e1ce7b67da7f6ec0761a7?s=96&d=mm&r=g","caption":"Kate\u0159ina Markvartov\u00e1"},"url":"https:\/\/svetkamene.eu\/index.php\/author\/ka-markvartovagmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/8099"}],"collection":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/comments?post=8099"}],"version-history":[{"count":1,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/8099\/revisions"}],"predecessor-version":[{"id":8101,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/8099\/revisions\/8101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/media\/2494"}],"wp:attachment":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/media?parent=8099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/categories?post=8099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/tags?post=8099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}