{"id":7438,"date":"2022-06-06T04:00:00","date_gmt":"2022-06-06T02:00:00","guid":{"rendered":"https:\/\/svetkamene.eu\/?p=7438"},"modified":"2022-06-08T13:10:46","modified_gmt":"2022-06-08T11:10:46","slug":"entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2","status":"publish","type":"post","link":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/","title":{"rendered":"ENTDECKEN SIE DEN CARRARA-MARMOR &#8211; BIANCO ORDINARIO, GUIDE TEIL 2"},"content":{"rendered":"\n<p><strong>W\u00e4hrend viele Menschen in Polen noch nie etwas von Ordinario (kurz f\u00fcr Bianco Ordinario) geh\u00f6rt haben, verwenden ihn die Italiener schon seit Jahrhunderten. <br>Im Italienischen bedeutet &#8222;bianco&#8220; &#8222;wei\u00df&#8220; und &#8222;ordinario&#8220; ist ein Adjektiv, das sich auf etwas Gew\u00f6hnliches, Typisches oder \u00dcbliches bezieht.<\/strong><\/p>\n\n\n\n<p>Der Bianco Ordinario ist der am meisten abgebaute Marmor in den Apuanischen Alpen. Der Name Ordinario k\u00f6nnte jedoch urspr\u00fcnglich mit den h\u00e4ufigsten Verwendungszwecken dieser Marmorsorte in Verbindung gebracht worden sein und nicht mit der blo\u00dfen Tatsache, dass er verf\u00fcgbar war. Wei\u00dfer Marmor, der den Anforderungen der Bildhauer entspricht (d.h. das Material, das f\u00fcr das Schneiden von kleinsten Details und zufolge dessen extrem realistischen Statuen geeignet ist), wurde als &#8222;Bianco Statuario&#8220; bezeichnet, w\u00e4hrend der wei\u00dfe Marmor, der ideal f\u00fcr die Herstellung so genannter &#8222;opere ordinarie&#8220; oder &#8222;lavori ordinari&#8220; oder &#8222;gew\u00f6hnlicher, allt\u00e4glicher, typischer\u201c Realisierungen wie Fu\u00dfb\u00f6den, Fassaden, Verkleidungen, Treppen, Kamine, Platten und einfache Alt\u00e4re, B\u00fcsten, Denkm\u00e4ler oder Gartenskulpturen ist, wird Bianco Ordinario gennant.<\/p>\n\n\n\n<p>Beide Theorien sind gleicherma\u00dfen glaubw\u00fcrdig, aber keine von ihnen wurde bisher \u00fcberzeugend best\u00e4tigt. Die Bedeutung, die dem Namen Ordinario in der Carrara-Gemeinde zugeschrieben wird, bezieht sich auf die betr\u00e4chtliche Menge des abgebauten Materials, aber es gibt Aufzeichnungen in Fachpublikationen aus dem 19. Jahrhundert, aus denen klar hervorgeht, dass das Adjektiv &#8222;ordinario&#8220; als Teil des Namens des Marmors dessen Verwendung f\u00fcr &#8222;opere ordinarie&#8220;, &#8222;lavori ordinari&#8220;, &#8222;usi comuni&#8220; und &#8222;statue comuni e colossali&#8220; beschreibt.<\/p>\n\n\n\n<p>Auf Italienisch:<\/p>\n\n\n\n<p>&#8211; Das Wort &#8222;statuario&#8220; ist ein Adjektiv, das in Bezug auf Marmor w\u00f6rtlich &#8222;f\u00fcr die Herstellung von Statuen geeignet&#8220; bedeutet;<\/p>\n\n\n\n<p>&#8211; &#8222;opere&#8220;, &#8222;lavori&#8220; bedeutet &#8222;Werke&#8220;, &#8222;Arbeiten&#8220;;<\/p>\n\n\n\n<p>&#8211; &#8222;usi comuni&#8220; bedeutet im Italienischen &#8222;allgemeine, weit verbreitete Verwendung&#8220;;<\/p>\n\n\n\n<p>&#8211; &#8222;statua comuni e colossali&#8220; sind gro\u00dfe skulpturale Werke, die im \u00f6ffentlichen Raum und in St\u00e4dten verwendet werden.<\/p>\n\n\n\n<p><strong>Zusammenfassung:<\/strong><br>Die Namen des Apuanischen Marmors k\u00f6nnen unterschiedliche Bedeutungen haben, je nachdem, wann, wo und von wem sie verwendet werden. Folglich k\u00f6nnen mehrere Bedeutungen demselben Namen zugeordnet werden.<\/p>\n\n\n\n<p><strong>Die wichtigsten Merkmale von Ordinaria sind<\/strong>:<br>feines bis mittleres Korn, ein Hintergrund in den Farben Perlgrau, Hellgrau, Grau, Mattwei\u00df und Dunkelgrau sowie hellgraue Adern und Flecken, die oft unscharf, kurz und verstreut sind und nicht in einer Richtung verlaufen. Einige Untertypen von Bianco Ordinario haben auch graubraune, orangefarbene Ausw\u00fcchse.<\/p>\n\n\n\n<p>Wenn man den angegebenen Text liest, hat man den Eindruck, dass er ein vertrautes Material beschreibt: Bianco Carrara. Tats\u00e4chlich handelt es sich bei Bianco Carrara um Bianco Ordinario aus den Carrara-Steinbr\u00fcchen.<\/p>\n\n\n\n<p>Warum ist der Name &#8222;Ordinario&#8220; in der Welt nicht beliebt? Warum wird er heute, von wenigen Ausnahmen abgesehen, nicht einmal mehr von den italienischen Plattenexporteuren verwendet?\\<\/p>\n\n\n\n<p>Aus unserer Sicht gibt es daf\u00fcr drei Hauptgr\u00fcnde:<br>Erstens wurde der Begriff Ordinario im Laufe der Zeit f\u00fcr zu viele wei\u00dfe Marmore verwendet &#8211; auch f\u00fcr Dolomit und f\u00fcr solche, die nicht aus den Apuanischen Alpen stammen. Die in Carrara ans\u00e4ssigen Unternehmen waren sich dieser Situation bewusst und sahen sich veranlasst, den lokalen Ordinario in Bezug auf die K\u00f6rnung (kompakt, fein bis mittel), die Zusammensetzung und die technischen Merkmale zu definieren. Daher wurden die Bezeichnungen Bianco Carrara Ordinario oder Bianco Ordinario di Carrara angenommen, die dann auf das einfachere Bianco Carrara verk\u00fcrzt wurden. Was ist mit all den Ordinarien aus anderen Gebieten der Apuanischen Alpen? In den meisten F\u00e4llen benennen ihn die Unternehmer, die diesen Marmor vermarkten, nach den Regionen, in denen er abgebaut wird, mit dem Begriff &#8222;Bianco&#8220;, der ihm vorangeht.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p id=\"block-ce2872ed-ca84-4425-8175-0584b1d7b341\">Quelle: <a href=\"https:\/\/www.kurierkamieniarski.pl\/artykuly\/o-kamieniu\/1176-odkryj-marmury-karraryjskie-przewodnik-cz-2-bianco-ordinario.html\">Kurier kamieniarski<\/a><\/p>\n\n\n\n<p id=\"block-1f7fa4fd-bc0e-461a-8aff-d05cc931f47a\">Autor: Omnistone.pl | Publiziert: 28.&nbsp;02.&nbsp;2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend viele Menschen in Polen noch nie etwas von Ordinario (kurz f\u00fcr Bianco Ordinario) geh\u00f6rt&#8230;<\/p>\n","protected":false},"author":32,"featured_media":2327,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[378],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ENTDECKEN SIE DEN CARRARA-MARMOR - BIANCO ORDINARIO, GUIDE TEIL 2 - Sv\u011bt Kamene<\/title>\n<meta name=\"description\" content=\"Zat\u00edmco mnoho lid\u00ed v Polsku nikdy nesly\u0161elo o Ordinariu (zkratka pro Bianco Ordinario), Italov\u00e9 pou\u017e\u00edvaj\u00ed toto jm\u00e9no po cel\u00e1 stalet\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTDECKEN SIE DEN CARRARA-MARMOR - BIANCO ORDINARIO, GUIDE TEIL 2 - Sv\u011bt Kamene\" \/>\n<meta property=\"og:description\" content=\"Zat\u00edmco mnoho lid\u00ed v Polsku nikdy nesly\u0161elo o Ordinariu (zkratka pro Bianco Ordinario), Italov\u00e9 pou\u017e\u00edvaj\u00ed toto jm\u00e9no po cel\u00e1 stalet\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Sv\u011bt Kamene\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-06T02:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-08T11:10:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/104_car2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napsal(a)\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ale\u0161 Vachu\u0161ka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Odhadovan\u00e1 doba \u010dten\u00ed\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/svetkamene.eu\/#website\",\"url\":\"https:\/\/svetkamene.eu\/\",\"name\":\"Sv\u011bt Kamene\",\"description\":\"Port\u00e1l informuj\u00edc\u00ed o v\u0161em co souvis\u00ed s kamenem\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/svetkamene.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"cs\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/#primaryimage\",\"url\":\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/104_car2.jpg\",\"contentUrl\":\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/104_car2.jpg\",\"width\":640,\"height\":480},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/#webpage\",\"url\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/\",\"name\":\"ENTDECKEN SIE DEN CARRARA-MARMOR - BIANCO ORDINARIO, GUIDE TEIL 2 - Sv\u011bt Kamene\",\"isPartOf\":{\"@id\":\"https:\/\/svetkamene.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/#primaryimage\"},\"datePublished\":\"2022-06-06T02:00:00+00:00\",\"dateModified\":\"2022-06-08T11:10:46+00:00\",\"author\":{\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/1cf0663ef38389cd1ec5deab88437e04\"},\"description\":\"Zat\u00edmco mnoho lid\u00ed v Polsku nikdy nesly\u0161elo o Ordinariu (zkratka pro Bianco Ordinario), Italov\u00e9 pou\u017e\u00edvaj\u00ed toto jm\u00e9no po cel\u00e1 stalet\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\/\/svetkamene.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTDECKEN SIE DEN CARRARA-MARMOR &#8211; BIANCO ORDINARIO, GUIDE TEIL 2\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/1cf0663ef38389cd1ec5deab88437e04\",\"name\":\"Ale\u0161 Vachu\u0161ka\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3b0db7dae3f05599081057d1ea848a8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3b0db7dae3f05599081057d1ea848a8c?s=96&d=mm&r=g\",\"caption\":\"Ale\u0161 Vachu\u0161ka\"},\"url\":\"https:\/\/svetkamene.eu\/index.php\/author\/vachuska-alessgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ENTDECKEN SIE DEN CARRARA-MARMOR - BIANCO ORDINARIO, GUIDE TEIL 2 - Sv\u011bt Kamene","description":"Zat\u00edmco mnoho lid\u00ed v Polsku nikdy nesly\u0161elo o Ordinariu (zkratka pro Bianco Ordinario), Italov\u00e9 pou\u017e\u00edvaj\u00ed toto jm\u00e9no po cel\u00e1 stalet\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/","og_locale":"cs_CZ","og_type":"article","og_title":"ENTDECKEN SIE DEN CARRARA-MARMOR - BIANCO ORDINARIO, GUIDE TEIL 2 - Sv\u011bt Kamene","og_description":"Zat\u00edmco mnoho lid\u00ed v Polsku nikdy nesly\u0161elo o Ordinariu (zkratka pro Bianco Ordinario), Italov\u00e9 pou\u017e\u00edvaj\u00ed toto jm\u00e9no po cel\u00e1 stalet\u00ed.","og_url":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/","og_site_name":"Sv\u011bt Kamene","article_published_time":"2022-06-06T02:00:00+00:00","article_modified_time":"2022-06-08T11:10:46+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/104_car2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Napsal(a)":"Ale\u0161 Vachu\u0161ka","Odhadovan\u00e1 doba \u010dten\u00ed":"4 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/svetkamene.eu\/#website","url":"https:\/\/svetkamene.eu\/","name":"Sv\u011bt Kamene","description":"Port\u00e1l informuj\u00edc\u00ed o v\u0161em co souvis\u00ed s kamenem","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svetkamene.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"cs"},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/#primaryimage","url":"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/104_car2.jpg","contentUrl":"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/104_car2.jpg","width":640,"height":480},{"@type":"WebPage","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/#webpage","url":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/","name":"ENTDECKEN SIE DEN CARRARA-MARMOR - BIANCO ORDINARIO, GUIDE TEIL 2 - Sv\u011bt Kamene","isPartOf":{"@id":"https:\/\/svetkamene.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/#primaryimage"},"datePublished":"2022-06-06T02:00:00+00:00","dateModified":"2022-06-08T11:10:46+00:00","author":{"@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/1cf0663ef38389cd1ec5deab88437e04"},"description":"Zat\u00edmco mnoho lid\u00ed v Polsku nikdy nesly\u0161elo o Ordinariu (zkratka pro Bianco Ordinario), Italov\u00e9 pou\u017e\u00edvaj\u00ed toto jm\u00e9no po cel\u00e1 stalet\u00ed.","breadcrumb":{"@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/06\/entdecken-sie-den-carrara-marmor-bianco-ordinario-guide-teil-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/svetkamene.eu\/"},{"@type":"ListItem","position":2,"name":"ENTDECKEN SIE DEN CARRARA-MARMOR &#8211; BIANCO ORDINARIO, GUIDE TEIL 2"}]},{"@type":"Person","@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/1cf0663ef38389cd1ec5deab88437e04","name":"Ale\u0161 Vachu\u0161ka","image":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3b0db7dae3f05599081057d1ea848a8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b0db7dae3f05599081057d1ea848a8c?s=96&d=mm&r=g","caption":"Ale\u0161 Vachu\u0161ka"},"url":"https:\/\/svetkamene.eu\/index.php\/author\/vachuska-alessgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/7438"}],"collection":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/comments?post=7438"}],"version-history":[{"count":1,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/7438\/revisions"}],"predecessor-version":[{"id":7439,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/7438\/revisions\/7439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/media\/2327"}],"wp:attachment":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/media?parent=7438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/categories?post=7438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/tags?post=7438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}