{"id":6682,"date":"2022-05-31T21:28:28","date_gmt":"2022-05-31T19:28:28","guid":{"rendered":"https:\/\/beta.svetkamene.eu\/?p=6682"},"modified":"2022-05-31T21:28:28","modified_gmt":"2022-05-31T19:28:28","slug":"soll-man-tun-wenn-es-keine-messe-gibt","status":"publish","type":"post","link":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/","title":{"rendered":"SOLL MAN TUN, WENN ES KEINE MESSE GIBT"},"content":{"rendered":"\n<p><strong>Messen haben eine sehr lange Geschichte. Es gen\u00fcgt festzustellen, dass in Polen die erste Erw\u00e4hnung von Jahrm\u00e4rkten in Aufzeichnungen aus dem Jahr 1065 erscheint. Das Recht, Jahrm\u00e4rkte zu veranstalten, geh\u00f6rte zu den grundlegenden Privilegien der St\u00e4dte. Manchmal fanden sie ein- oder zweimal pro Woche statt. Damals konnte man Messen als eine Form von Verkauf und Kauf definieren.<\/strong><strong><\/strong><\/p>\n\n\n\n<div style=\"height:47px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong><br><\/strong>Seit der Kapitalismus geboren worden war, entwickelten sich die Messen sehr schnell. Die Warenmessen wurden durch \u201eProduktionsausstellungen\u201c und \u201eallgemeine Ausstellungen\u201c ersetzt &#8211; wie sie damals genannt wurden. In den Worten der damaligen Zeit handelte es sich um \u201eMuster\u201c- und \u201eModell\u201c-Messen. In den Jahren 1900-1920 entstanden die gr\u00f6\u00dften Ausstellungszentren der Welt &#8211; Paris, Lyon, Mailand, K\u00f6ln und viele andere. Damals wurde auch die Messe in Posen gegr\u00fcndet (1920). Es stellte sich heraus, dass diese Form, die H\u00e4ndlerkontakte erm\u00f6glicht hatte, gut angenommen wurde. Im Jahr 1923 gab es europaweit bereits 454 Messepl\u00e4tze. Sp\u00e4ter wurde das Konzept der Messen als Ort f\u00fcr direkte Kontakte vom sich entwickelnden Marketing genutzt, und so entstanden Messen in der Form, wie wir sie in der Gegenwart kennen. Heute gibt es weltweit etwa 2.500 gro\u00dfe Messezentren. Bei den Veranstaltern handelt es sich in der Mehrzahl um kommerzielle Unternehmen. So viel zur Einf\u00fchrung.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img src=\"https:\/\/beta.svetkamene.eu\/wp-content\/uploads\/2022\/05\/108_42_01-1.jpg\" alt=\"\" class=\"wp-image-6683\"\/><\/figure><\/div>\n\n\n\n<div style=\"height:44px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Zeitgen\u00f6ssische Messen sind Ausstellungen, auf denen Hersteller und Vertreiber von Waren ihre Angebote pr\u00e4sentieren und Besucher Vertr\u00e4ge abschlie\u00dfen. Es ist auch ein Ort, an dem bestimmte Entwicklungsrichtungen gef\u00f6rdert werden k\u00f6nnen, auch im Design. Es stellt sich die Frage, inwieweit solche Veranstaltungen derzeit f\u00fcr alle Teilnehmer attraktiv sind.<\/p>\n\n\n\n<p><br>Messen haben sich unter bestimmten \u00e4u\u00dferen Bedingungen dynamisch entwickelt. Sie erreichten ihren H\u00f6hepunkt in einer Zeit, in der Kommunikation und Verkehr stark eingeschr\u00e4nkt waren und die Menschen die M\u00f6glichkeit eines pers\u00f6nlichen Kontakts sehr sch\u00e4tzten, der viel mehr bot als blo\u00dfer Telefonanruf von eher mittelm\u00e4\u00dfiger Qualit\u00e4t.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img src=\"https:\/\/beta.svetkamene.eu\/wp-content\/uploads\/2022\/05\/108_42_02-1.jpg\" alt=\"\" class=\"wp-image-6684\"\/><\/figure><\/div>\n\n\n\n<div style=\"height:43px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Die Kommunikationstechnologien haben sich in den letzten Jahren stark weiterentwickelt. Es bestehen bisher unbekannte M\u00f6glichkeiten der Angebotspr\u00e4sentation. Die Unternehmen haben mitunter sehr umfangreiche Websites und ver\u00f6ffentlichen nicht nur Parameter, Angebote und Fotos, sondern auch Filme und interaktive Pr\u00e4sentationen. Auch in der Kommunikation selbst haben sich gro\u00dfe Ver\u00e4nderungen vollzogen. Die modernen Technologien erm\u00f6glichen Videoverbindungen zwischen den Gespr\u00e4chspartnern, so dass der Eindruck eines direkten Kontakts fast greifbar ist.<\/p>\n\n\n\n<p>Es ist merkw\u00fcrdig, dass die Messeveranstalter im Zusammenhang mit diesen technologischen Ver\u00e4nderungen nicht besonders nach neuen Motivationen f\u00fcr die Besucher und folglich auch f\u00fcr die Aussteller gesucht haben. Es gibt immer noch ein Standardangebot: ein Bankett, ein paar Vortr\u00e4ge, eine Ausstellung, manchmal ein Vortrag einer bekannten Pers\u00f6nlichkeit&#8230; Es fehlt eindeutig an einer interessanten und konsequent verfolgten Mission der Organisation &#8211; einer Handlungsrichtung. Die Ver\u00e4nderungen erfolgten nicht von einem Jahr zum n\u00e4chsten. Es war ein langfristiger Prozess. In unserer Branche hat wahrscheinlich nur das italienische Unternehmen Marmomac seine Hausaufgaben gemacht. Sie hat sich stark auf die Unterst\u00fctzung und Pr\u00e4sentation neuer Ideen im Bereich Design und Basistechnologien konzentriert. Au\u00dferdem unterst\u00fctzt sie die Steinindustrie mit zahlreichen Aktivit\u00e4ten.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img src=\"https:\/\/beta.svetkamene.eu\/wp-content\/uploads\/2022\/05\/108_42_03-1.jpg\" alt=\"Obsah obr\u00e1zku text, interi\u00e9r, osoba\n\nPopis byl vytvo\u0159en automaticky\" class=\"wp-image-6685\"\/><\/figure><\/div>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Nat\u00fcrlich ist die Messe eine Gelegenheit, die angebotenen Waren \u201ephysisch\u201c anzufassen. Und das war wohl auch der Grund f\u00fcr den von den meisten Messeveranstaltern eingeschlagenen Weg: m\u00f6glichst viel Ausstellungsfl\u00e4che zu m\u00f6glichst geringen Kosten zu verkaufen. Aber ist die M\u00f6glichkeit f\u00fcr die Kunden, das Angebot \u201eanzufassen\u201c, die hohen Kosten f\u00fcr die Teilnahme an der Messe wert? Man sollte die bereits erw\u00e4hnten pers\u00f6nlichen Treffen nicht vergessen. Ein ganz wichtiges Element, das die Messebesucher anzieht, ist das Bed\u00fcrfnis nach direkten sozialen Kontakten. Beim Besuch einer Ausstellung treffen wir viele Freunde, die wir sonst nur gelegentlich sehen. Solche Begegnungen sind die Attraktion der Messe. Es besteht die M\u00f6glichkeit, von Angesicht zu Angesicht zu sprechen. Es besteht auch die M\u00f6glichkeit zum Erfahrungsaustausch. Und die entspannte Atmosph\u00e4re l\u00e4dt dazu ein, Geheimnisse auszutauschen, \u00fcber die man am Telefon nur selten spricht.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Quelle: <a href=\"https:\/\/www.kurierkamieniarski.pl\/\" target=\"_blank\" rel=\"noreferrer noopener\">Kurier kamieniarski<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Messen haben eine sehr lange Geschichte. Es gen\u00fcgt festzustellen, dass in Polen die erste Erw\u00e4hnung&#8230;<\/p>\n","protected":false},"author":31,"featured_media":6678,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[674],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SOLL MAN TUN, WENN ES KEINE MESSE GIBT - Sv\u011bt Kamene<\/title>\n<meta name=\"description\" content=\"Se zrodem kapitalismu v modern\u00ed dob\u011b pak do\u0161lo k rychl\u00e9mu rozmachu veletrh\u016f. Objevily se \u201ev\u00fdrobkov\u00e9 v\u00fdstavy\u201c nebo tak\u00e9 \u201eobecn\u00e9 v\u00fdstavy\u201c,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOLL MAN TUN, WENN ES KEINE MESSE GIBT - Sv\u011bt Kamene\" \/>\n<meta property=\"og:description\" content=\"Se zrodem kapitalismu v modern\u00ed dob\u011b pak do\u0161lo k rychl\u00e9mu rozmachu veletrh\u016f. Objevily se \u201ev\u00fdrobkov\u00e9 v\u00fdstavy\u201c nebo tak\u00e9 \u201eobecn\u00e9 v\u00fdstavy\u201c,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/\" \/>\n<meta property=\"og:site_name\" content=\"Sv\u011bt Kamene\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-31T19:28:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napsal(a)\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martina Hovorkov\u00e1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Odhadovan\u00e1 doba \u010dten\u00ed\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/svetkamene.eu\/#website\",\"url\":\"https:\/\/svetkamene.eu\/\",\"name\":\"Sv\u011bt Kamene\",\"description\":\"Port\u00e1l informuj\u00edc\u00ed o v\u0161em co souvis\u00ed s kamenem\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/svetkamene.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"cs\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/#webpage\",\"url\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/\",\"name\":\"SOLL MAN TUN, WENN ES KEINE MESSE GIBT - Sv\u011bt Kamene\",\"isPartOf\":{\"@id\":\"https:\/\/svetkamene.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/#primaryimage\"},\"datePublished\":\"2022-05-31T19:28:28+00:00\",\"dateModified\":\"2022-05-31T19:28:28+00:00\",\"author\":{\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/63ecc926d3eacc6248c818270a6bbe23\"},\"description\":\"Se zrodem kapitalismu v modern\u00ed dob\u011b pak do\u0161lo k rychl\u00e9mu rozmachu veletrh\u016f. Objevily se \u201ev\u00fdrobkov\u00e9 v\u00fdstavy\u201c nebo tak\u00e9 \u201eobecn\u00e9 v\u00fdstavy\u201c,\",\"breadcrumb\":{\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\/\/svetkamene.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SOLL MAN TUN, WENN ES KEINE MESSE GIBT\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/63ecc926d3eacc6248c818270a6bbe23\",\"name\":\"Martina Hovorkov\u00e1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab907f59548aa3bd3e4b7d266ef68fd1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab907f59548aa3bd3e4b7d266ef68fd1?s=96&d=mm&r=g\",\"caption\":\"Martina Hovorkov\u00e1\"},\"url\":\"https:\/\/svetkamene.eu\/index.php\/author\/hovorkova\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SOLL MAN TUN, WENN ES KEINE MESSE GIBT - Sv\u011bt Kamene","description":"Se zrodem kapitalismu v modern\u00ed dob\u011b pak do\u0161lo k rychl\u00e9mu rozmachu veletrh\u016f. Objevily se \u201ev\u00fdrobkov\u00e9 v\u00fdstavy\u201c nebo tak\u00e9 \u201eobecn\u00e9 v\u00fdstavy\u201c,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/","og_locale":"cs_CZ","og_type":"article","og_title":"SOLL MAN TUN, WENN ES KEINE MESSE GIBT - Sv\u011bt Kamene","og_description":"Se zrodem kapitalismu v modern\u00ed dob\u011b pak do\u0161lo k rychl\u00e9mu rozmachu veletrh\u016f. Objevily se \u201ev\u00fdrobkov\u00e9 v\u00fdstavy\u201c nebo tak\u00e9 \u201eobecn\u00e9 v\u00fdstavy\u201c,","og_url":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/","og_site_name":"Sv\u011bt Kamene","article_published_time":"2022-05-31T19:28:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Napsal(a)":"Martina Hovorkov\u00e1","Odhadovan\u00e1 doba \u010dten\u00ed":"3 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/svetkamene.eu\/#website","url":"https:\/\/svetkamene.eu\/","name":"Sv\u011bt Kamene","description":"Port\u00e1l informuj\u00edc\u00ed o v\u0161em co souvis\u00ed s kamenem","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svetkamene.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"cs"},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/#primaryimage","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/#webpage","url":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/","name":"SOLL MAN TUN, WENN ES KEINE MESSE GIBT - Sv\u011bt Kamene","isPartOf":{"@id":"https:\/\/svetkamene.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/#primaryimage"},"datePublished":"2022-05-31T19:28:28+00:00","dateModified":"2022-05-31T19:28:28+00:00","author":{"@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/63ecc926d3eacc6248c818270a6bbe23"},"description":"Se zrodem kapitalismu v modern\u00ed dob\u011b pak do\u0161lo k rychl\u00e9mu rozmachu veletrh\u016f. Objevily se \u201ev\u00fdrobkov\u00e9 v\u00fdstavy\u201c nebo tak\u00e9 \u201eobecn\u00e9 v\u00fdstavy\u201c,","breadcrumb":{"@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/05\/31\/soll-man-tun-wenn-es-keine-messe-gibt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/svetkamene.eu\/"},{"@type":"ListItem","position":2,"name":"SOLL MAN TUN, WENN ES KEINE MESSE GIBT"}]},{"@type":"Person","@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/63ecc926d3eacc6248c818270a6bbe23","name":"Martina Hovorkov\u00e1","image":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab907f59548aa3bd3e4b7d266ef68fd1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab907f59548aa3bd3e4b7d266ef68fd1?s=96&d=mm&r=g","caption":"Martina Hovorkov\u00e1"},"url":"https:\/\/svetkamene.eu\/index.php\/author\/hovorkova\/"}]}},"_links":{"self":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/6682"}],"collection":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/comments?post=6682"}],"version-history":[{"count":0,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/6682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/media?parent=6682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/categories?post=6682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/tags?post=6682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}