{"id":5562,"date":"2020-12-08T18:33:00","date_gmt":"2020-12-08T17:33:00","guid":{"rendered":"https:\/\/beta.svetkamene.eu\/?p=5562"},"modified":"2021-10-05T19:14:16","modified_gmt":"2021-10-05T17:14:16","slug":"woher-kommt-der-makadam-teil-1","status":"publish","type":"post","link":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/","title":{"rendered":"Woher kommt der Makadam? &#8211; Teil 1"},"content":{"rendered":"\n<p><strong>Wege, Pfade, Stra\u00dfen, Autobahnen, Eisenbahnen, sogenannte Landstra\u00dfen sind die &#8222;Arterien der Industrie&#8220;, ohne die wir nicht auskommen.<\/strong><\/p>\n\n\n\n<div style=\"height:46px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Schotter, Steinsplitt oder kurz Steingemisch ist wohl das einfachste Steinprodukt. Es wird \u00fcberwiegend in der Bauindustrie eingesetzt und ist aus der modernen Welt nicht mehr wegzudenken. Seine Herstellung ist heute eine eigene Industrie mit fortschrittlichen Technologien. Die heutige Zeit stellt hohe Anforderungen an die Hersteller von Zuschlagstoffen, sowohl in Bezug auf die Qualit\u00e4t des Gesteins als auch auf die Reinheit der K\u00f6rnigkeit. Diese Branche ist auch mit der Maschinenbau-, Metallurgie- und Chemieindustrie verbunden und bietet viele interessante Arbeitsm\u00f6glichkeiten.<\/p>\n\n\n\n<div style=\"height:47px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4>Eine kleine Geschichte \u2013 R\u00f6mer<\/h4>\n\n\n\n<p>Lassen Sie uns ein wenig in die Geschichte schauen. Die Frage ist: Wurde Schotter in der Vergangenheit verwendet, um die damaligen Stra\u00dfen zu reparieren? Sicherlich ja, aber es war sozusagen &#8222;das, was zur Hand war&#8220;. Offensichtlich wurden Sand oder Schotter, die durch die nat\u00fcrliche Verwitterung von Gesteinen entstanden sind, in gro\u00dfem Umfang verwendet. Es war also keine zielgerichtete Produktion.<\/p>\n\n\n\n<p>Das R\u00f6mische Reich hat uns davon \u00fcberzeugt, wie wichtig es ist, neue, qualitativ hochwertige Kommunikationsnetze zu schaffen und sie in Ordnung zu halten. Es stellte hohe Anforderungen an deren Bau und Instandhaltung, da die Stra\u00dfen von milit\u00e4rischer und strategischer Bedeutung waren.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"242\" height=\"208\" src=\"https:\/\/beta.svetkamene.eu\/wp-content\/uploads\/2021\/10\/01-14.jpg\" alt=\"\" class=\"wp-image-5563\"\/><\/figure><\/div>\n\n\n\n<p>Die R\u00f6mer waren wahrscheinlich die ersten, die feste Grunds\u00e4tze und Anforderungen f\u00fcr den Bau und die regelm\u00e4\u00dfige Instandhaltung von Stra\u00dfen festlegten, die im Wesentlichen noch heute g\u00fcltig sind. Insbesondere wurde gro\u00dfer Wert auf eine solide und stabile Basis mit geschlossener Oberfl\u00e4che gelegt. Jede Stra\u00dfe war leicht ausgeh\u00f6hlt und hatte an jedem Rand eine kleine Rinne zur Wasserableitung.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"369\" height=\"136\" src=\"https:\/\/beta.svetkamene.eu\/wp-content\/uploads\/2021\/10\/02-1.png\" alt=\"\" class=\"wp-image-5564\" srcset=\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/10\/02-1.png 369w, https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/10\/02-1-300x111.png 300w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/figure><\/div>\n\n\n\n<p>Alles, was in Reichweite war, wurde genutzt. Selbst f\u00fcr eine damalige Sklavenhaltergesellschaft war es ein kostspieliger und zeitaufw\u00e4ndiger Bauvorgang, der sich aber auszahlte. Einige der r\u00f6mischen Stra\u00dfen sind heute noch in Gebrauch. Am Bau der Stra\u00dfen nahm ausschlie\u00dflich die Armee Anteil. Jeder Soldat wurde in grundlegenden Baut\u00e4tigkeiten ausgebildet und ein kleiner Spaten war Teil seiner milit\u00e4rischen Ausr\u00fcstung.<\/p>\n\n\n\n<p>Das Mittelalter hat den Bau von Stra\u00dfen nicht wesentlich beeinflusst. Es nutzte weiterhin das, was von den R\u00f6mern \u00fcbrig geblieben war, und wenn eine neue Stra\u00dfe entstand, war sie meist unbefestigt, auf einem Bodenunterbau ohne besondere regelm\u00e4\u00dfige Wartung. Aber es w\u00e4re unfair gegen\u00fcber dem Mittelalter, nicht zu erw\u00e4hnen, dass die ersten Schotterstra\u00dfen im 15. Jahrhundert auftauchten. Aufgrund der hohen Kosten erreichte diese perfekte Methode des Stra\u00dfenbaus jedoch keine breitere Anwendung im Leben der damaligen Gesellschaft.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Quelle: <a href=\"http:\/\/www.lomyatezba.cz\">www.lomyatezba.cz<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wege, Pfade, Stra\u00dfen, Autobahnen, Eisenbahnen, sogenannte Landstra\u00dfen sind die &#8222;Arterien der Industrie&#8220;, ohne die wir&#8230;<\/p>\n","protected":false},"author":31,"featured_media":3004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[370],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Woher kommt der Makadam? - Teil 1 - Sv\u011bt Kamene<\/title>\n<meta name=\"description\" content=\"St\u0159edov\u011bk do v\u00fdstavby komunikac\u00ed nijak z\u00e1sadn\u011b nezas\u00e1hl. U\u017e\u00edval d\u00e1l, co z\u016fstalo po \u0158\u00edmanech. Nov\u00e1 cesta byla v\u011btsinou pra\u0161n\u00e1.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Woher kommt der Makadam? - Teil 1 - Sv\u011bt Kamene\" \/>\n<meta property=\"og:description\" content=\"St\u0159edov\u011bk do v\u00fdstavby komunikac\u00ed nijak z\u00e1sadn\u011b nezas\u00e1hl. U\u017e\u00edval d\u00e1l, co z\u016fstalo po \u0158\u00edmanech. Nov\u00e1 cesta byla v\u011btsinou pra\u0161n\u00e1.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Sv\u011bt Kamene\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-08T17:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-05T17:14:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/90c57ca8306bf148ef75c82407e738af_M.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"497\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napsal(a)\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martina Hovorkov\u00e1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Odhadovan\u00e1 doba \u010dten\u00ed\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/svetkamene.eu\/#website\",\"url\":\"https:\/\/svetkamene.eu\/\",\"name\":\"Sv\u011bt Kamene\",\"description\":\"Port\u00e1l informuj\u00edc\u00ed o v\u0161em co souvis\u00ed s kamenem\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/svetkamene.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"cs\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/#primaryimage\",\"url\":\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/90c57ca8306bf148ef75c82407e738af_M.jpg\",\"contentUrl\":\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/90c57ca8306bf148ef75c82407e738af_M.jpg\",\"width\":746,\"height\":497},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/#webpage\",\"url\":\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/\",\"name\":\"Woher kommt der Makadam? - Teil 1 - Sv\u011bt Kamene\",\"isPartOf\":{\"@id\":\"https:\/\/svetkamene.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/#primaryimage\"},\"datePublished\":\"2020-12-08T17:33:00+00:00\",\"dateModified\":\"2021-10-05T17:14:16+00:00\",\"author\":{\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/63ecc926d3eacc6248c818270a6bbe23\"},\"description\":\"St\u0159edov\u011bk do v\u00fdstavby komunikac\u00ed nijak z\u00e1sadn\u011b nezas\u00e1hl. U\u017e\u00edval d\u00e1l, co z\u016fstalo po \u0158\u00edmanech. Nov\u00e1 cesta byla v\u011btsinou pra\u0161n\u00e1.\",\"breadcrumb\":{\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\/\/svetkamene.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Woher kommt der Makadam? &#8211; Teil 1\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/63ecc926d3eacc6248c818270a6bbe23\",\"name\":\"Martina Hovorkov\u00e1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab907f59548aa3bd3e4b7d266ef68fd1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab907f59548aa3bd3e4b7d266ef68fd1?s=96&d=mm&r=g\",\"caption\":\"Martina Hovorkov\u00e1\"},\"url\":\"https:\/\/svetkamene.eu\/index.php\/author\/hovorkova\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Woher kommt der Makadam? - Teil 1 - Sv\u011bt Kamene","description":"St\u0159edov\u011bk do v\u00fdstavby komunikac\u00ed nijak z\u00e1sadn\u011b nezas\u00e1hl. U\u017e\u00edval d\u00e1l, co z\u016fstalo po \u0158\u00edmanech. Nov\u00e1 cesta byla v\u011btsinou pra\u0161n\u00e1.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/","og_locale":"cs_CZ","og_type":"article","og_title":"Woher kommt der Makadam? - Teil 1 - Sv\u011bt Kamene","og_description":"St\u0159edov\u011bk do v\u00fdstavby komunikac\u00ed nijak z\u00e1sadn\u011b nezas\u00e1hl. U\u017e\u00edval d\u00e1l, co z\u016fstalo po \u0158\u00edmanech. Nov\u00e1 cesta byla v\u011btsinou pra\u0161n\u00e1.","og_url":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/","og_site_name":"Sv\u011bt Kamene","article_published_time":"2020-12-08T17:33:00+00:00","article_modified_time":"2021-10-05T17:14:16+00:00","og_image":[{"width":746,"height":497,"url":"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/90c57ca8306bf148ef75c82407e738af_M.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Napsal(a)":"Martina Hovorkov\u00e1","Odhadovan\u00e1 doba \u010dten\u00ed":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/svetkamene.eu\/#website","url":"https:\/\/svetkamene.eu\/","name":"Sv\u011bt Kamene","description":"Port\u00e1l informuj\u00edc\u00ed o v\u0161em co souvis\u00ed s kamenem","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svetkamene.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"cs"},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/#primaryimage","url":"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/90c57ca8306bf148ef75c82407e738af_M.jpg","contentUrl":"https:\/\/svetkamene.eu\/wp-content\/uploads\/2021\/01\/90c57ca8306bf148ef75c82407e738af_M.jpg","width":746,"height":497},{"@type":"WebPage","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/#webpage","url":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/","name":"Woher kommt der Makadam? - Teil 1 - Sv\u011bt Kamene","isPartOf":{"@id":"https:\/\/svetkamene.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/#primaryimage"},"datePublished":"2020-12-08T17:33:00+00:00","dateModified":"2021-10-05T17:14:16+00:00","author":{"@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/63ecc926d3eacc6248c818270a6bbe23"},"description":"St\u0159edov\u011bk do v\u00fdstavby komunikac\u00ed nijak z\u00e1sadn\u011b nezas\u00e1hl. U\u017e\u00edval d\u00e1l, co z\u016fstalo po \u0158\u00edmanech. Nov\u00e1 cesta byla v\u011btsinou pra\u0161n\u00e1.","breadcrumb":{"@id":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2020\/12\/08\/woher-kommt-der-makadam-teil-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/svetkamene.eu\/"},{"@type":"ListItem","position":2,"name":"Woher kommt der Makadam? &#8211; Teil 1"}]},{"@type":"Person","@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/63ecc926d3eacc6248c818270a6bbe23","name":"Martina Hovorkov\u00e1","image":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab907f59548aa3bd3e4b7d266ef68fd1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab907f59548aa3bd3e4b7d266ef68fd1?s=96&d=mm&r=g","caption":"Martina Hovorkov\u00e1"},"url":"https:\/\/svetkamene.eu\/index.php\/author\/hovorkova\/"}]}},"_links":{"self":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/5562"}],"collection":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/comments?post=5562"}],"version-history":[{"count":1,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/5562\/revisions"}],"predecessor-version":[{"id":5565,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/5562\/revisions\/5565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/media\/3004"}],"wp:attachment":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/media?parent=5562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/categories?post=5562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/tags?post=5562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}