{"id":11059,"date":"2022-06-22T08:08:53","date_gmt":"2022-06-22T06:08:53","guid":{"rendered":"https:\/\/svetkamene.eu\/?p=11059"},"modified":"2022-06-28T22:17:25","modified_gmt":"2022-06-28T20:17:25","slug":"die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich","status":"publish","type":"post","link":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/","title":{"rendered":"Die neu entwickelten Betriebsfl\u00fcssigkeiten von Total f\u00fcr Bau- und Bergbaumaschinen senken den Kraftstoffverbrauch erheblich"},"content":{"rendered":"<p><strong>Neu entwickelte Maschinen f\u00fcr die Gewinnungstechnik und Abbruchmaschinen&nbsp; erfordern ein ausgekl\u00fcgeltes Wartungssystem, um einen langfristigen und zuverl\u00e4ssigen Betrieb zu gew\u00e4hrleisten. Zu diesem System geh\u00f6rt zweifellos die Auswahl und Anwendung der geeigneten Schmier- und Betriebsfl\u00fcssigkeiten, einschlie\u00dflich der \u00dcberwachung ihres technischen Zustands w\u00e4hrend des Betriebs, um unerw\u00fcnschte technische Ausf\u00e4lle zu vermeiden.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Die Firma TOTAL Petroleum and Energy entwickelt seit langem Schmierstoffe und Zustands\u00fcberwachungssysteme f\u00fcr Baumaschinen, Abbruch- und Bergbaumaschinen, wobei der Schwerpunkt auf der wirtschaftlichen und \u00f6kologischen Leistung von Schmierstoffen liegt.<\/p>\n<p>Die neuesten Schmierstofftypen sind besonders auf den wirtschaftlichen Betrieb von Mechanismen ausgerichtet, d.h. auf die Anwendung von Formulierungen sogenannter FE-Schmierstoffe (\u201eFuel Economy\u201c) mit erh\u00f6hter St\u00fctzwirkung, die den Kraftstoffverbrauch der Maschine im Betrieb reduzieren. Die maximale Wirkung kann durch den gleichzeitigen Einsatz von FE-Schmierstoffen in allen Maschinenaggregaten (Verbrennungsmotor, Getriebe, hydraulische \u00dcbertragungsmechanismen, Achsgetriebe&#8230;) erzielt werden.<\/p>\n<p>&nbsp;<\/p>\n<h4>TOTAL-Motoren\u00f6le &#8211; RUBIA WORKS<\/h4>\n<p>Unter dem Namen Label RUBIA WORKS 4000 hat TOTAL eine Reihe moderner, umweltfreundlicher und wirtschaftlicher Motoren\u00f6le f\u00fcr Abbruchmaschinen und Lader entwickelt, die mit konventionellen Verbrennungsmotoren und insbesondere mit Motoren mit Abgasreinigungs- und -Minderungseinrichtungen (DPF, AGR-Ventile f\u00fcr die Abgasr\u00fcckf\u00fchrung, selektive katalytische Reduktion von Stickoxiden &#8211; AD Blue-Technologie) ausgestattet sind&#8230;<\/p>\n<p>Diese neue Motoren\u00f6lserie besteht aus dem Mineral\u00f6l RUBIA WORKS 4000&nbsp;15W-40 und dem synthetischen Leichtlauf\u00f6l RUBIA WORKS 4000 FE 10W-30, das eine deutliche Kraftstoffeinsparung erm\u00f6glicht (Fuel Economy &#8211; Kraftstoffeinsparung von 3 bis 5&nbsp;% je nach Betriebsart). In beiden F\u00e4llen handelt es sich um aschearme Motoren\u00f6le, die die neueste Leistungsnorm API CK-4 erf\u00fcllen, die strengere Anforderungen insbesondere f\u00fcr den anspruchsvollen Betrieb von Dieselverbrennungsmotoren in Nutzfahrzeugen, Baumaschinen und Abbaumaschinen mit Emissionsminderungsvorrichtungen definiert. H\u00f6heres Niveau der technischen Parameter der RUBIA WORKS 4000 \u00d6le:<\/p>\n<ul>\n<li>H\u00e4lt den Motor bis zu 70% sauberer, was die Bildung von Ablagerungen angeht (CATERPILLAR C13 Test Limit &#8211; Kolbengruppe)<\/li>\n<li>Reduziert die \u00d6loxidation bei h\u00f6heren Temperaturen um 70% (Volvo T13 Test Limit)<\/li>\n<li>50% geringere Abnutzung des Verteilermechanismus (Cummins ISB Test Limit)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Quelle: <a href=\"https:\/\/www.lomyatezba.cz\/\">Lomy a&nbsp;t\u011b\u017eba<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neu entwickelte Maschinen f\u00fcr die Gewinnungstechnik und Abbruchmaschinen&nbsp; erfordern ein ausgekl\u00fcgeltes Wartungssystem, um einen langfristigen&#8230;<\/p>\n","protected":false},"author":31,"featured_media":8963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[370],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Die neu entwickelten Betriebsfl\u00fcssigkeiten von Total f\u00fcr Bau- und Bergbaumaschinen senken den Kraftstoffverbrauch erheblich - Sv\u011bt Kamene<\/title>\n<meta name=\"description\" content=\"zaji\u0161t\u011bn\u00ed spolehliv\u00e9ho provozu - sofistikovan\u00fd syst\u00e9m \u00fadr\u017eby - volba a aplikace vhodn\u00fdch typ\u016f maziv a provozn\u00edch n\u00e1pln\u00ed\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die neu entwickelten Betriebsfl\u00fcssigkeiten von Total f\u00fcr Bau- und Bergbaumaschinen senken den Kraftstoffverbrauch erheblich - Sv\u011bt Kamene\" \/>\n<meta property=\"og:description\" content=\"zaji\u0161t\u011bn\u00ed spolehliv\u00e9ho provozu - sofistikovan\u00fd syst\u00e9m \u00fadr\u017eby - volba a aplikace vhodn\u00fdch typ\u016f maziv a provozn\u00edch n\u00e1pln\u00ed\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/\" \/>\n<meta property=\"og:site_name\" content=\"Sv\u011bt Kamene\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-22T06:08:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-28T20:17:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2022\/06\/003.png\" \/>\n\t<meta property=\"og:image:width\" content=\"648\" \/>\n\t<meta property=\"og:image:height\" content=\"364\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napsal(a)\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martina Hovorkov\u00e1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Odhadovan\u00e1 doba \u010dten\u00ed\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/svetkamene.eu\/#website\",\"url\":\"https:\/\/svetkamene.eu\/\",\"name\":\"Sv\u011bt Kamene\",\"description\":\"Port\u00e1l informuj\u00edc\u00ed o v\u0161em co souvis\u00ed s kamenem\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/svetkamene.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"cs\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/#primaryimage\",\"url\":\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2022\/06\/003.png\",\"contentUrl\":\"https:\/\/svetkamene.eu\/wp-content\/uploads\/2022\/06\/003.png\",\"width\":648,\"height\":364},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/#webpage\",\"url\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/\",\"name\":\"Die neu entwickelten Betriebsfl\u00fcssigkeiten von Total f\u00fcr Bau- und Bergbaumaschinen senken den Kraftstoffverbrauch erheblich - Sv\u011bt Kamene\",\"isPartOf\":{\"@id\":\"https:\/\/svetkamene.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/#primaryimage\"},\"datePublished\":\"2022-06-22T06:08:53+00:00\",\"dateModified\":\"2022-06-28T20:17:25+00:00\",\"author\":{\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/63ecc926d3eacc6248c818270a6bbe23\"},\"description\":\"zaji\u0161t\u011bn\u00ed spolehliv\u00e9ho provozu - sofistikovan\u00fd syst\u00e9m \u00fadr\u017eby - volba a aplikace vhodn\u00fdch typ\u016f maziv a provozn\u00edch n\u00e1pln\u00ed\",\"breadcrumb\":{\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\/\/svetkamene.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die neu entwickelten Betriebsfl\u00fcssigkeiten von Total f\u00fcr Bau- und Bergbaumaschinen senken den Kraftstoffverbrauch erheblich\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/63ecc926d3eacc6248c818270a6bbe23\",\"name\":\"Martina Hovorkov\u00e1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/svetkamene.eu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab907f59548aa3bd3e4b7d266ef68fd1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab907f59548aa3bd3e4b7d266ef68fd1?s=96&d=mm&r=g\",\"caption\":\"Martina Hovorkov\u00e1\"},\"url\":\"https:\/\/svetkamene.eu\/index.php\/author\/hovorkova\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die neu entwickelten Betriebsfl\u00fcssigkeiten von Total f\u00fcr Bau- und Bergbaumaschinen senken den Kraftstoffverbrauch erheblich - Sv\u011bt Kamene","description":"zaji\u0161t\u011bn\u00ed spolehliv\u00e9ho provozu - sofistikovan\u00fd syst\u00e9m \u00fadr\u017eby - volba a aplikace vhodn\u00fdch typ\u016f maziv a provozn\u00edch n\u00e1pln\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/","og_locale":"cs_CZ","og_type":"article","og_title":"Die neu entwickelten Betriebsfl\u00fcssigkeiten von Total f\u00fcr Bau- und Bergbaumaschinen senken den Kraftstoffverbrauch erheblich - Sv\u011bt Kamene","og_description":"zaji\u0161t\u011bn\u00ed spolehliv\u00e9ho provozu - sofistikovan\u00fd syst\u00e9m \u00fadr\u017eby - volba a aplikace vhodn\u00fdch typ\u016f maziv a provozn\u00edch n\u00e1pln\u00ed","og_url":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/","og_site_name":"Sv\u011bt Kamene","article_published_time":"2022-06-22T06:08:53+00:00","article_modified_time":"2022-06-28T20:17:25+00:00","og_image":[{"width":648,"height":364,"url":"https:\/\/svetkamene.eu\/wp-content\/uploads\/2022\/06\/003.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Napsal(a)":"Martina Hovorkov\u00e1","Odhadovan\u00e1 doba \u010dten\u00ed":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/svetkamene.eu\/#website","url":"https:\/\/svetkamene.eu\/","name":"Sv\u011bt Kamene","description":"Port\u00e1l informuj\u00edc\u00ed o v\u0161em co souvis\u00ed s kamenem","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svetkamene.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"cs"},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/#primaryimage","url":"https:\/\/svetkamene.eu\/wp-content\/uploads\/2022\/06\/003.png","contentUrl":"https:\/\/svetkamene.eu\/wp-content\/uploads\/2022\/06\/003.png","width":648,"height":364},{"@type":"WebPage","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/#webpage","url":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/","name":"Die neu entwickelten Betriebsfl\u00fcssigkeiten von Total f\u00fcr Bau- und Bergbaumaschinen senken den Kraftstoffverbrauch erheblich - Sv\u011bt Kamene","isPartOf":{"@id":"https:\/\/svetkamene.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/#primaryimage"},"datePublished":"2022-06-22T06:08:53+00:00","dateModified":"2022-06-28T20:17:25+00:00","author":{"@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/63ecc926d3eacc6248c818270a6bbe23"},"description":"zaji\u0161t\u011bn\u00ed spolehliv\u00e9ho provozu - sofistikovan\u00fd syst\u00e9m \u00fadr\u017eby - volba a aplikace vhodn\u00fdch typ\u016f maziv a provozn\u00edch n\u00e1pln\u00ed","breadcrumb":{"@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/svetkamene.eu\/index.php\/de\/2022\/06\/22\/die-neu-entwickelten-betriebsfluessigkeiten-von-total-fuer-bau-und-bergbaumaschinen-senken-den-kraftstoffverbrauch-erheblich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/svetkamene.eu\/"},{"@type":"ListItem","position":2,"name":"Die neu entwickelten Betriebsfl\u00fcssigkeiten von Total f\u00fcr Bau- und Bergbaumaschinen senken den Kraftstoffverbrauch erheblich"}]},{"@type":"Person","@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/63ecc926d3eacc6248c818270a6bbe23","name":"Martina Hovorkov\u00e1","image":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/svetkamene.eu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab907f59548aa3bd3e4b7d266ef68fd1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab907f59548aa3bd3e4b7d266ef68fd1?s=96&d=mm&r=g","caption":"Martina Hovorkov\u00e1"},"url":"https:\/\/svetkamene.eu\/index.php\/author\/hovorkova\/"}]}},"_links":{"self":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/11059"}],"collection":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/comments?post=11059"}],"version-history":[{"count":2,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/11059\/revisions"}],"predecessor-version":[{"id":11062,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/posts\/11059\/revisions\/11062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/media\/8963"}],"wp:attachment":[{"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/media?parent=11059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/categories?post=11059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svetkamene.eu\/index.php\/wp-json\/wp\/v2\/tags?post=11059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}